{"id":1742,"date":"2016-02-14T10:00:41","date_gmt":"2016-02-14T08:00:41","guid":{"rendered":"https:\/\/air-soft.gun-evasion.com\/blog\/?p=1742"},"modified":"2016-05-13T12:00:25","modified_gmt":"2016-05-13T10:00:25","slug":"equipements-airsoft-obligatoires","status":"publish","type":"post","link":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/","title":{"rendered":"Top 5 des \u00e9quipements Airsoft"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1747\" src=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg\" alt=\"\u00e9quipements airsoft\" width=\"215\" height=\"161\" srcset=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg 300w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-1024x768.jpg 1024w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-624x468.jpg 624w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" \/>On ne le r\u00e9p\u00e8tera jamais assez : quand on pratique l&rsquo;airsoft, il est <a href=\"https:\/\/air-soft.gun-evasion.com\/blog\/les-equipements-airsoft-indispensables\/\">indispensable de bien s&rsquo;\u00e9quiper<\/a>.\u00a0<\/strong><\/p>\n<p><strong>Protections oculaires, r\u00e9pliques longues, r\u00e9pliques de poing, gilet tactique et tenue, d\u00e9couvrez notre top 5 des \u00e9quipements airsoft les plus inconfortables\u00a0!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h2>\u00a0Les protections oculaires<\/h2>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1751\" src=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/lunettes-airsoft-150x150.jpg\" alt=\"lunettes-airsoft\" width=\"150\" height=\"150\" srcset=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/lunettes-airsoft-150x150.jpg 150w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/lunettes-airsoft-300x300.jpg 300w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/lunettes-airsoft.jpg 308w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>La plupart des d\u00e9butants, et m\u00eame certains joueurs plus exp\u00e9riment\u00e9s, <strong>privil\u00e9gient les r\u00e9pliques aux \u00e9quipements de protection.<\/strong><\/p>\n<p>Forc\u00e9ment, lorsqu&rsquo;il faut choisir entre une bonne <a href=\"https:\/\/air-soft.gun-evasion.com\/equipements\/equipement\/masques-lunettes.html?manufacturer=386&amp;price=20-30&amp;protections_type=289\">paire de lunettes airsoft<\/a>\u00a0et une belle r\u00e9plique longue un peu on\u00e9reuse, on est tent\u00e9 de se contenter de protections oculaires bas de gamme !<\/p>\n<p>Grave erreur\u00a0! Car, bien qu&rsquo;assez r\u00e9sistantes pour prot\u00e9ger convenablement les yeux du joueur, les protections oculaires les moins ch\u00e8res ont tout de m\u00eame la f\u00e2cheuse tendance \u00e0 bouger lorsque l&rsquo;on court et \u00e0 laisser la bu\u00e9e s&rsquo;installer un peu trop facilement.<\/p>\n<p>&nbsp;<\/p>\n<h2>La r\u00e9plique longue<\/h2>\n<p>&nbsp;<\/p>\n<p>Si la r\u00e9plique longue est g\u00e9n\u00e9ralement <strong>qualifi\u00e9e de \u00ab\u00a0r\u00e9plique principale\u00a0\u00bb<\/strong>, ce n&rsquo;est pas un hasard.<\/p>\n<p>C&rsquo;est bien souvent cette fameuse r\u00e9plique longue dans laquelle on est tent\u00e9 d&rsquo;investir le plus.<br \/>\nLogique puisque c&rsquo;est celle qui nous suivra partout, celle \u00e0 qui l&rsquo;on offrira les plus beaux accessoires, celle qu&rsquo;on personnalisera avec la plus grande attention afin de la rendre unique\u00a0!<\/p>\n<p>A noter que la majorit\u00e9 des joueurs d&rsquo;airsoft choisissent une <strong><a href=\"https:\/\/air-soft.gun-evasion.com\/repliques\/repliques-longues\/aeg.html\">r\u00e9plique longue AEG<\/a><\/strong>\u00a0ou un <a href=\"https:\/\/air-soft.gun-evasion.com\/repliques\/snipes.html\">sniper airsoft<\/a>\u00a0quand ils emm\u00e8nent une r\u00e9plique longue avec eux.<\/p>\n<p>&nbsp;<\/p>\n<h2>La r\u00e9plique de poing<\/h2>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1753\" src=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/replique-poing-150x150.jpg\" alt=\"replique-poing\" width=\"150\" height=\"150\" srcset=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/replique-poing-150x150.jpg 150w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/replique-poing-300x300.jpg 300w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/replique-poing.jpg 308w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>Parfois <strong>appel\u00e9e \u00ab\u00a0back-up\u00a0\u00bb<\/strong>, la r\u00e9plique de poing vous sera d&rsquo;une grande utilit\u00e9 dans plusieurs situations bien sp\u00e9cifiques.<\/p>\n<p>Tout d&rsquo;abord, lorsque vous vous <strong>retrouverez dans des b\u00e2timents<\/strong> ou tout du moins, dans des espaces confin\u00e9s o\u00f9 il vous sera parfois difficile, voire impossible, d&rsquo;utiliser votre r\u00e9plique longue.<\/p>\n<p>Ensuite, la r\u00e9plique de poing vous sera d&rsquo;un grand secours <strong>en cas de d\u00e9faillance de votre r\u00e9plique principale<\/strong>.<\/p>\n<p>Et si vous avez un minimum d&rsquo;exp\u00e9rience dans la pratique de l&rsquo;airsoft, vous saurez que c&rsquo;est le genre de mauvaise surprise qui arrive toujours au moment o\u00f9 l&rsquo;on s&rsquo;y attend le moins&#8230;<\/p>\n<p>&nbsp;<\/p>\n<h2>Le gilet tactique<\/h2>\n<p>&nbsp;<\/p>\n<p>Vous ne comptiez tout de m\u00eame pas transporter vos r\u00e9pliques, vos chargeurs et vos autres accessoires sous le bras\u00a0? Si c&rsquo;est le cas, on vous souhaite bien du courage\u00a0!<\/p>\n<p>La plupart des joueurs d&rsquo;airsoft investissent dans un <a href=\"https:\/\/air-soft.gun-evasion.com\/equipements\/equipement\/gilets-tactiques.html\">gilet tactique<\/a>\u00a0: un \u00e9quipement tr\u00e8s pratique qui leur permet de <strong>transporter leur mat\u00e9riel sans aucune contrainte<\/strong>.<\/p>\n<p>Mieux encore, les gilets tactiques sont tout <strong>sp\u00e9cialement con\u00e7us pour faciliter l&rsquo;acc\u00e8s aux accessoires les plus utilis\u00e9s<\/strong>, en particulier les chargeurs.<\/p>\n<p>&nbsp;<\/p>\n<h2>La tenue de camouflage<\/h2>\n<p>&nbsp;<\/p>\n<p>Le nerf de la guerre en airsoft, c&rsquo;est de <strong>voir sans \u00eatre vu<\/strong>.<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1755\" src=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/tenue-camouflage-150x150.jpg\" alt=\"tenue-camouflage\" width=\"225\" height=\"225\" srcset=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/tenue-camouflage-150x150.jpg 150w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/tenue-camouflage-300x300.jpg 300w, https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/tenue-camouflage.jpg 308w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>D&rsquo;o\u00f9 la dimension quasi incontournable de la <a href=\"https:\/\/air-soft.gun-evasion.com\/equipements\/tenues.html\">tenue d&rsquo;airsoft<\/a>\u00a0qui permet de se dissimuler tel un v\u00e9ritable cam\u00e9l\u00e9on.<\/p>\n<p>Attention n\u00e9anmoins \u00e0 bien <strong>choisir une tenue adapt\u00e9e \u00e0 l&rsquo;environnement de jeu<\/strong>.<br \/>\nIl ne s&rsquo;agirait pas d&rsquo;enfiler un treillis couleur sable si vous devez jouer en pleine for\u00eat. Autant directement vous balader avec une grosse cible rouge peinte dans le dos\u00a0!<\/p>\n<p>Vous pourrez retrouver sur notre site un grand choix de tenues d\u00e9di\u00e9es \u00e0 la pratique de l&rsquo;airsoft tous terrains confondus, allant\u00a0de la <a href=\"https:\/\/air-soft.gun-evasion.com\/\/equipements\/tenues\/combinaisons.html\">combinaison int\u00e9grale<\/a> \u00e0 la simple <a href=\"https:\/\/air-soft.gun-evasion.com\/equipements\/tenues\/vestes-de-combat.html\">veste de combat<\/a>.<\/p>\n<p>La tenue de camouflage, aussi importante soit-elle, ne doit n\u00e9anmoins pas vous faire oublier <strong>l&rsquo;indispensable paire de <a href=\"https:\/\/air-soft.gun-evasion.com\/equipements\/equipement\/chaussures.html\">chaussures montantes<\/a><\/strong>\u00a0!<\/p>\n<p>Un \u00e9quipement essentiel qui offre une protection maximale \u00e0 vos chevilles, m\u00eame dans les endroits les plus accident\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour d\u00e9couvrir l&rsquo;ensemble de nos \u00e9quipements airsoft, c&rsquo;est par ici :\u00a0<a href=\"https:\/\/air-soft.gun-evasion.com\/equipements.html\">https:\/\/air-soft.gun-evasion.com\/equipements.html<\/a> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On ne le r\u00e9p\u00e8tera jamais assez : quand on pratique l&rsquo;airsoft, il est indispensable de bien s&rsquo;\u00e9quiper.\u00a0 Protections oculaires, r\u00e9pliques longues, r\u00e9pliques de poing, gilet tactique et tenue, d\u00e9couvrez notre top 5 des \u00e9quipements airsoft les plus inconfortables\u00a0! &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[],"class_list":["post-1742","post","type-post","status-publish","format-standard","hentry","category-infos-conseils"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"D\u00e9butant en Airsoft ? Vous ne savez pas dans quel \u00e9quipement investir en priorit\u00e9 ? D\u00e9couvrez les 5 \u00e9quipements les plus populaires parmi les joueurs !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 5 des \u00e9quipements Airsoft\" \/>\n<meta property=\"og:description\" content=\"D\u00e9butant en Airsoft ? Vous ne savez pas dans quel \u00e9quipement investir en priorit\u00e9 ? D\u00e9couvrez les 5 \u00e9quipements les plus populaires parmi les joueurs !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/\" \/>\n<meta property=\"og:site_name\" content=\"Gun Evasion : Le Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/airsoftgunevasion\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-14T08:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-13T10:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gun Evasion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/#website\",\"url\":\"https:\/\/air-soft.gun-evasion.com\/blog\/\",\"name\":\"Gun Evasion : Le Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/air-soft.gun-evasion.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg\",\"contentUrl\":\"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#webpage\",\"url\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/\",\"name\":\"Top 5 des \\u00e9quipements Airsoft\",\"isPartOf\":{\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#primaryimage\"},\"datePublished\":\"2016-02-14T08:00:41+00:00\",\"dateModified\":\"2016-05-13T10:00:25+00:00\",\"author\":{\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/#\/schema\/person\/8fb9590a9b49720a6a172cb57af8f38a\"},\"description\":\"D\\u00e9butant en Airsoft ? Vous ne savez pas dans quel \\u00e9quipement investir en priorit\\u00e9 ? D\\u00e9couvrez les 5 \\u00e9quipements les plus populaires parmi les joueurs !\",\"breadcrumb\":{\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/air-soft.gun-evasion.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 5 des \\u00e9quipements Airsoft\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/#\/schema\/person\/8fb9590a9b49720a6a172cb57af8f38a\",\"name\":\"Gun Evasion\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/air-soft.gun-evasion.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c452fac495b0c85a6c3873851ea43c5c2da30ea719ef5c0ec9efa75e344be32e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c452fac495b0c85a6c3873851ea43c5c2da30ea719ef5c0ec9efa75e344be32e?s=96&d=mm&r=g\",\"caption\":\"Gun Evasion\"},\"url\":\"https:\/\/air-soft.gun-evasion.com\/blog\/author\/gunevasionadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"description":"D\u00e9butant en Airsoft ? Vous ne savez pas dans quel \u00e9quipement investir en priorit\u00e9 ? D\u00e9couvrez les 5 \u00e9quipements les plus populaires parmi les joueurs !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 5 des \u00e9quipements Airsoft","og_description":"D\u00e9butant en Airsoft ? Vous ne savez pas dans quel \u00e9quipement investir en priorit\u00e9 ? D\u00e9couvrez les 5 \u00e9quipements les plus populaires parmi les joueurs !","og_url":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/","og_site_name":"Gun Evasion : Le Blog","article_publisher":"https:\/\/www.facebook.com\/airsoftgunevasion","article_published_time":"2016-02-14T08:00:41+00:00","article_modified_time":"2016-05-13T10:00:25+00:00","og_image":[{"url":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg"}],"twitter_misc":{"\u00c9crit par":"Gun Evasion","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/#website","url":"https:\/\/air-soft.gun-evasion.com\/blog\/","name":"Gun Evasion : Le Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/air-soft.gun-evasion.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg","contentUrl":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-content\/uploads\/2016\/02\/sm-nwm-set2-9-1200x900-300x225.jpg"},{"@type":"WebPage","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#webpage","url":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/","name":"Top 5 des \u00e9quipements Airsoft","isPartOf":{"@id":"https:\/\/air-soft.gun-evasion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#primaryimage"},"datePublished":"2016-02-14T08:00:41+00:00","dateModified":"2016-05-13T10:00:25+00:00","author":{"@id":"https:\/\/air-soft.gun-evasion.com\/blog\/#\/schema\/person\/8fb9590a9b49720a6a172cb57af8f38a"},"description":"D\u00e9butant en Airsoft ? Vous ne savez pas dans quel \u00e9quipement investir en priorit\u00e9 ? D\u00e9couvrez les 5 \u00e9quipements les plus populaires parmi les joueurs !","breadcrumb":{"@id":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/equipements-airsoft-obligatoires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/air-soft.gun-evasion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 5 des \u00e9quipements Airsoft"}]},{"@type":"Person","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/#\/schema\/person\/8fb9590a9b49720a6a172cb57af8f38a","name":"Gun Evasion","image":{"@type":"ImageObject","@id":"https:\/\/air-soft.gun-evasion.com\/blog\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/c452fac495b0c85a6c3873851ea43c5c2da30ea719ef5c0ec9efa75e344be32e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c452fac495b0c85a6c3873851ea43c5c2da30ea719ef5c0ec9efa75e344be32e?s=96&d=mm&r=g","caption":"Gun Evasion"},"url":"https:\/\/air-soft.gun-evasion.com\/blog\/author\/gunevasionadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/posts\/1742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/comments?post=1742"}],"version-history":[{"count":15,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/posts\/1742\/revisions"}],"predecessor-version":[{"id":1936,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/posts\/1742\/revisions\/1936"}],"wp:attachment":[{"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/media?parent=1742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/categories?post=1742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/air-soft.gun-evasion.com\/blog\/wp-json\/wp\/v2\/tags?post=1742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}